{"id":2720,"date":"2026-02-01T00:05:41","date_gmt":"2026-02-01T00:05:41","guid":{"rendered":"https:\/\/casaisabel.es\/?p=2720---aca7a0e3-54e2-4bc4-b24a-d04d8922a21c"},"modified":"2026-02-01T00:05:41","modified_gmt":"2026-02-01T00:05:41","slug":"historia-sobre-el-puerto-de-valencia","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/it\/historia-sobre-el-puerto-de-valencia\/","title":{"rendered":"Historia sobre el Puerto de Valencia"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Valencia<\/strong> es una ciudad perfecta para albergar turistas de todas las nacionalidades, tiene una <strong>temperatura ideal<\/strong> durante todo el a\u00f1o y se pueden visitar muchos lugares interesantes. Se puede elegir desde visitar su <strong>casco antiguo<\/strong>, hasta acercarse a una <a href=\"https:\/\/casaisabel.es\/it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>arrocer\u00eda en la playa<\/strong><\/a> y degustar una exquisita <strong>paella<\/strong> en el magn\u00edfico Puerto de Valencia.<!--more--><\/p>\n<p style=\"text-align: justify;\">El <strong>Puerto de Valencia<\/strong> es uno de los m\u00e1s importantes en cuanto a tr\u00e1fico comercial del Mediterr\u00e1neo, y tambi\u00e9n acoge un tr\u00e1fico regular de pasajeros dirigidos a todos los puntos de las costas mediterr\u00e1neas.<\/p>\n<p style=\"text-align: justify;\">Aunque la l\u00ednea de la <strong>costa de Valencia<\/strong> fuera un obst\u00e1culo para la creaci\u00f3n del puerto, debido a la <strong>carencia de abrigo natural<\/strong>, hay constancia de <strong>actividades comerciales desde el siglo VI antes de Cristo<\/strong>. Pero fue mucho despu\u00e9s, en <strong>marzo de 1491<\/strong> cuando el rey <strong>Fernando el Cat\u00f3lico<\/strong> otorg\u00f3 privilegios a un caballero valenciano y el emplazamiento del puerto empez\u00f3 a explotarse propiamente como puerto.<\/p>\n<p style=\"text-align: justify;\">A partir de entonces, se hicieron numerosas <strong>reformas para acondicionar debidamente el emplazamiento portuario<\/strong>. Durante el <strong>siglo XV<\/strong> se construy\u00f3 el conocido <strong>\u00abpont de fusta\u00bb<\/strong> y tambi\u00e9n se construy\u00f3 la <strong>ampliaci\u00f3n de las ataranzas<\/strong>. En el <strong>siglo XVII<\/strong> se concedi\u00f3 a Valencia el <strong>derecho de ser puerto de tr\u00e1fico de mercanc\u00edas para otros reinos<\/strong>, hecho que hizo que las obras de acondicionamiento del puerto tuvieran m\u00e1xima prioridad y urgencia. Esta urgencia permiti\u00f3 que el puerto mejorara considerablemente para adaptarse a las necesidades del momento.<\/p>\n<p style=\"text-align: justify;\">En el <strong>a\u00f1o 2005<\/strong> y con motivo de la <strong>32\u00aa America&#8217;s Cup<\/strong>, el <strong>Puerto de Valencia<\/strong> hizo importantes transformaciones, entre ellas la <strong>separaci\u00f3n de las zonas comerciales y de ocio<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En conclusi\u00f3n, el <strong>Puerto de Valencia<\/strong> es uno de los lugares m\u00e1s extraordinarios de la capital, con <strong>vistas maravillosas<\/strong>, y puede ser contemplado desde cualquier <strong>restaurante de la playa Malvarrosa<\/strong> degustando el plato t\u00edpico de la ciudad, la paella.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.flickr.com\/photos\/guillermomorales\/3789407234\/in\/photolist-bVfzuW-faJQ5p-eAr4Y1-eAhSQZ-eAr1ey-4GampL-bVA8ro-dPU6um-a\" target=\"_blank\" rel=\"noopener noreferrer\">Imagen<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Valencia es una ciudad perfecta para albergar turistas de todas las nacionalidades, tiene una temperatura ideal durante todo el a\u00f1o y se pueden visitar muchos lugares interesantes. Se puede elegir desde visitar su casco antiguo, hasta acercarse a una arrocer\u00eda en la playa y degustar una exquisita paella en el magn\u00edfico Puerto de Valencia.<\/p>","protected":false},"author":2,"featured_media":2721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[16,5,17],"class_list":["post-2720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-emblematicos-de-valencia","tag-puerto-de-valencia","tag-valencia","tag-zona-del-puerto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Historia sobre el Puerto de Valencia - Casa Isabel<\/title>\n<meta name=\"description\" content=\"Se puede elegir desde visitar su casco antiguo, hasta acercarse a una arrocer\u00eda en la playa y degustar una paella en el magn\u00edfico Puerto de Valencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/it\/historia-sobre-el-puerto-de-valencia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia sobre el Puerto de Valencia - Casa Isabel\" \/>\n<meta property=\"og:description\" content=\"Se puede elegir desde visitar su casco antiguo, hasta acercarse a una arrocer\u00eda en la playa y degustar una paella en el magn\u00edfico Puerto de Valencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/it\/historia-sobre-el-puerto-de-valencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-01T00:05:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"869\" \/>\n\t<meta property=\"og:image:height\" content=\"301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"Historia sobre el Puerto de Valencia\",\"datePublished\":\"2026-02-01T00:05:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg\",\"keywords\":[\"puerto de valencia\",\"Valencia\",\"zona del puerto\"],\"articleSection\":[\"Lugares emblem\u00e1ticos de Valencia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/\",\"url\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/\",\"name\":\"Historia sobre el Puerto de Valencia - Casa Isabel\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg\",\"datePublished\":\"2026-02-01T00:05:41+00:00\",\"description\":\"Se puede elegir desde visitar su casco antiguo, hasta acercarse a una arrocer\u00eda en la playa y degustar una paella en el magn\u00edfico Puerto de Valencia.\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg\",\"width\":869,\"height\":301,\"caption\":\"cisabel-puerto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historia sobre el Puerto de Valencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/it\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historia sobre el Puerto de Valencia - Casa Isabel","description":"Se puede elegir desde visitar su casco antiguo, hasta acercarse a una arrocer\u00eda en la playa y degustar una paella en el magn\u00edfico Puerto de Valencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/it\/historia-sobre-el-puerto-de-valencia\/","og_locale":"it_IT","og_type":"article","og_title":"Historia sobre el Puerto de Valencia - Casa Isabel","og_description":"Se puede elegir desde visitar su casco antiguo, hasta acercarse a una arrocer\u00eda en la playa y degustar una paella en el magn\u00edfico Puerto de Valencia.","og_url":"https:\/\/casaisabel.es\/it\/historia-sobre-el-puerto-de-valencia\/","og_site_name":"Casa Isabel","article_published_time":"2026-02-01T00:05:41+00:00","og_image":[{"width":869,"height":301,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"Historia sobre el Puerto de Valencia","datePublished":"2026-02-01T00:05:41+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/"},"wordCount":336,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg","keywords":["puerto de valencia","Valencia","zona del puerto"],"articleSection":["Lugares emblem\u00e1ticos de Valencia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/","url":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/","name":"Historia sobre el Puerto de Valencia - Casa Isabel","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg","datePublished":"2026-02-01T00:05:41+00:00","description":"Se puede elegir desde visitar su casco antiguo, hasta acercarse a una arrocer\u00eda en la playa y degustar una paella en el magn\u00edfico Puerto de Valencia.","breadcrumb":{"@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel-puerto.jpg","width":869,"height":301,"caption":"cisabel-puerto"},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/historia-sobre-el-puerto-de-valencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"Historia sobre el Puerto de Valencia"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/it\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts\/2720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/comments?post=2720"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts\/2720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/media\/2721"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/media?parent=2720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/categories?post=2720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/tags?post=2720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}