{"id":2716,"date":"2026-01-31T00:06:42","date_gmt":"2026-01-31T00:06:42","guid":{"rendered":"https:\/\/casaisabel.es\/?p=2716---71ce1082-e69b-45a6-aaee-93810d8634ac"},"modified":"2026-01-31T00:06:42","modified_gmt":"2026-01-31T00:06:42","slug":"paella-y-tardeo-la-combinacion-perfecta","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/it\/paella-y-tardeo-la-combinacion-perfecta\/","title":{"rendered":"Paella y tardeo: la combinaci\u00f3n perfecta"},"content":{"rendered":"<p style=\"text-align: justify;\">Hace ya tiempo que el <a href=\"http:\/\/www.elmundo.es\/comunidad-valenciana\/2015\/01\/11\/54b25288268e3e99548b456c.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>tardeo<\/strong><\/a>\u00a0se ha implantado como alternativa al ocio nocturno. Esta costumbre, cuyo nombre resulta de la combinaci\u00f3n de <strong>\u201ctarde\u201d y \u201ctapeo\u201d<\/strong>, consiste en tomar unas copas, ir a una discoteca o hacer ambas cosas antes del anochecer. Tiene incluso su hashtag en Twitter, <strong>#yotardeo<\/strong>, y ha sido consagrado este a\u00f1o con la <strong>primera edici\u00f3n de la Ruta del Tardeo<\/strong>, que se pudo disfrutar hasta el 21 de junio.<!--more--><\/p>\n<p style=\"text-align: justify;\">Muchas personas han hecho suya esta tendencia para huir de la masificaci\u00f3n de algunos locales por la noche, o para tratar de evitar los horrores de la resaca. Hay una creciente preferencia por <strong>opciones m\u00e1s saludables de entretenimiento<\/strong>, y en ese sentido no es extra\u00f1o que <strong>Valencia<\/strong> se haya convertido en la <strong>cuna del tardeo<\/strong>: ir a una <strong>arrocer\u00eda<\/strong> a comer una buena <strong>paella<\/strong> es la mejor preparaci\u00f3n para ir de fiesta.<\/p>\n<p style=\"text-align: justify;\">La <strong>paella<\/strong> es uno de los platos m\u00e1s valorados no solo por los turistas extranjeros, sino tambi\u00e9n por los espa\u00f1oles, y no \u00fanicamente por su sabor: siempre ha estado <strong>asociada a la celebraci\u00f3n<\/strong>, al <strong>encuentro social,<\/strong> y ya solo por eso parece un <strong>buen preludio para un plan de tarde con los amigos<\/strong>. Pero son en especial sus propiedades nutricionales las que la convierten en una elecci\u00f3n inmejorable.<\/p>\n<p style=\"text-align: justify;\">Cualquiera de los numerosos <strong>platos de arroz<\/strong> que ofrece la <strong>gastronom\u00eda de Valencia<\/strong> <strong>(el arroz a banda, negro, al horno&#8230;)<\/strong> resulta ligero y f\u00e1cilmente digerible. Adem\u00e1s, su alto contenido en <strong>hidratos de carbono<\/strong> proporciona energ\u00eda de liberaci\u00f3n lenta que, sin duda, resulta \u00fatil para mantenerse activo largas horas. Si adem\u00e1s se saborea cualquiera de estos platos <strong>a pie de playa<\/strong>, por ejemplo en alg\u00fan <a href=\"https:\/\/casaisabel.es\/it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>restaurante de la Malvarrosa<\/strong><\/a>, la experiencia sensorial resulta ya completa para dar comienzo a cualquier plan festivo.<\/p>\n<p style=\"text-align: justify;\">Y es que desde un principio <strong>el mar, el tardeo y la dieta mediterr\u00e1nea estaban hechos para confluir<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.flickr.com\/photos\/tuttotutto\/7489907524\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fuente de imagen<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Hace ya tiempo que el tardeo\u00a0se ha implantado como alternativa al ocio nocturno. Esta costumbre, cuyo nombre resulta de la combinaci\u00f3n de \u201ctarde\u201d y \u201ctapeo\u201d, consiste en tomar unas copas, ir a una discoteca o hacer ambas cosas antes del anochecer. Tiene incluso su hashtag en Twitter, #yotardeo, y ha sido consagrado este a\u00f1o con [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7,3],"tags":[14,15],"class_list":["post-2716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-eventos","category-gastronomia","tag-paella","tag-tardeo-en-valencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paella y tardeo: la combinaci\u00f3n perfecta - Casa Isabel<\/title>\n<meta name=\"description\" content=\"Hace ya tiempo que el tardeo se ha implantado como alternativa al ocio nocturno. Esta costumbre resulta de la combinaci\u00f3n de \u201ctarde\u201d y \u201ctapeo\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/it\/paella-y-tardeo-la-combinacion-perfecta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paella y tardeo: la combinaci\u00f3n perfecta - Casa Isabel\" \/>\n<meta property=\"og:description\" content=\"Hace ya tiempo que el tardeo se ha implantado como alternativa al ocio nocturno. Esta costumbre resulta de la combinaci\u00f3n de \u201ctarde\u201d y \u201ctapeo\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/it\/paella-y-tardeo-la-combinacion-perfecta\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-31T00:06:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"882\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"Paella y tardeo: la combinaci\u00f3n perfecta\",\"datePublished\":\"2026-01-31T00:06:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/\"},\"wordCount\":342,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg\",\"keywords\":[\"paella\",\"tardeo en valencia\"],\"articleSection\":[\"Actualidad y eventos\",\"Gastronom\u00eda\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/\",\"url\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/\",\"name\":\"Paella y tardeo: la combinaci\u00f3n perfecta - Casa Isabel\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg\",\"datePublished\":\"2026-01-31T00:06:42+00:00\",\"description\":\"Hace ya tiempo que el tardeo se ha implantado como alternativa al ocio nocturno. Esta costumbre resulta de la combinaci\u00f3n de \u201ctarde\u201d y \u201ctapeo\u201d\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg\",\"width\":2560,\"height\":882,\"caption\":\"cisabel_tardeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paella y tardeo: la combinaci\u00f3n perfecta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/it\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paella y tardeo: la combinaci\u00f3n perfecta - Casa Isabel","description":"Hace ya tiempo que el tardeo se ha implantado como alternativa al ocio nocturno. Esta costumbre resulta de la combinaci\u00f3n de \u201ctarde\u201d y \u201ctapeo\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/it\/paella-y-tardeo-la-combinacion-perfecta\/","og_locale":"it_IT","og_type":"article","og_title":"Paella y tardeo: la combinaci\u00f3n perfecta - Casa Isabel","og_description":"Hace ya tiempo que el tardeo se ha implantado como alternativa al ocio nocturno. Esta costumbre resulta de la combinaci\u00f3n de \u201ctarde\u201d y \u201ctapeo\u201d","og_url":"https:\/\/casaisabel.es\/it\/paella-y-tardeo-la-combinacion-perfecta\/","og_site_name":"Casa Isabel","article_published_time":"2026-01-31T00:06:42+00:00","og_image":[{"width":2560,"height":882,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"Paella y tardeo: la combinaci\u00f3n perfecta","datePublished":"2026-01-31T00:06:42+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/"},"wordCount":342,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg","keywords":["paella","tardeo en valencia"],"articleSection":["Actualidad y eventos","Gastronom\u00eda"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/","url":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/","name":"Paella y tardeo: la combinaci\u00f3n perfecta - Casa Isabel","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg","datePublished":"2026-01-31T00:06:42+00:00","description":"Hace ya tiempo que el tardeo se ha implantado como alternativa al ocio nocturno. Esta costumbre resulta de la combinaci\u00f3n de \u201ctarde\u201d y \u201ctapeo\u201d","breadcrumb":{"@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_tardeo-scaled.jpg","width":2560,"height":882,"caption":"cisabel_tardeo"},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/paella-y-tardeo-la-combinacion-perfecta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"Paella y tardeo: la combinaci\u00f3n perfecta"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/it\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts\/2716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/comments?post=2716"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts\/2716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/media\/2717"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/media?parent=2716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/categories?post=2716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/tags?post=2716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}