{"id":2467,"date":"2026-01-26T00:17:18","date_gmt":"2026-01-26T00:17:18","guid":{"rendered":"https:\/\/casaisabel.es\/?p=2467---fd2805f0-7a14-4877-a04c-d08dc5c47e29"},"modified":"2026-01-26T00:17:18","modified_gmt":"2026-01-26T00:17:18","slug":"como-preparar-una-buena-mousse-en-valencia","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/it\/como-preparar-una-buena-mousse-en-valencia\/","title":{"rendered":"C\u00f3mo preparar una mousse valenciana"},"content":{"rendered":"<p style=\"text-align: justify;\">Una <a href=\"http:\/\/www.moussedechocolate.net\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>mousse<\/strong><\/a> es un irresistible <strong>postre<\/strong> de origen franc\u00e9s que se puede tomar, tanto salado como dulce, pero <strong>siempre bien fr\u00edo<\/strong>. La m\u00e1s conocida y deliciosa es la de <strong>chocolate<\/strong>, que pudo ser creada a finales del XIX por el pintor postimpresionista <strong>Toulouse-Lautrec<\/strong>, que frecuentaba las tabernas de <strong>Montmartre<\/strong>. Otras teor\u00edas sit\u00faan su autor\u00eda en el artesano espa\u00f1ol <strong>Manuel Cordero<\/strong>, que durante el <strong>Sitio de Astorga<\/strong> elabor\u00f3 una <strong>\u00abespuma de chocolate\u00bb<\/strong> para el emperador franc\u00e9s, que qued\u00f3 impresionado. Independientemente de su origen, este delicioso postre se puede degustar en <strong>Valencia<\/strong>, tras una sabrosa<strong> paella<\/strong> en su bella <strong>playa.<!--more--><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Pasos para elaborar una buena mousse de chocolate<\/strong><\/p>\n<p style=\"text-align: justify;\">La <a href=\"http:\/\/www.abc.com.py\/articulos\/la-mousse-de-chocolate-186982.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>receta<\/strong> es muy sencilla<\/a> y requiere, para unas <strong>4 personas<\/strong>, <strong>chocolate negro para postres (150 g)<\/strong>, <strong>nata para montar o manteca (50 g)<\/strong>, <strong>4 huevos y az\u00facar (30 g)<\/strong>. Para elaborarla, se parte el chocolate y se vierte en un bol, junto con la nata, el az\u00facar y 2 cucharadas de agua. Se derrite lentamente al ba\u00f1o Mar\u00eda, mientras se separan 3 yemas de las claras y se a\u00f1aden al recipiente, una vez que forme una crema homog\u00e9nea. Despu\u00e9s, integrar bien y retirar del fuego. Posteriormente, se baten las claras a punto de nieve y, con movimientos suaves y envolventes, se a\u00f1aden a la crema de chocolate. Una vez concluido en <a href=\"http:\/\/www.comolosquesos.com\/2011\/05\/la-receta-de-mousse-de-chocolate-mas.html\" target=\"_blank\" rel=\"noopener noreferrer\">proceso<\/a>, se vierten en copas y se dejan enfriar hasta el momento de servir. Si se opta por la nata o la manteca, el sabor del chocolate ser\u00e1 m\u00e1s suave o fuerte, respectivamente.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s de la tradicional receta, existen <strong>variedades de mousse<\/strong>, desde las que introducen un peque\u00f1o detalle, como <strong>frutas del bosque y menta<\/strong>; hasta las <strong>esponjosas mousses de pl\u00e1tano<\/strong>, que incluir\u00edan, adem\u00e1s, <strong>mermelada de grosellas<\/strong> o un delicioso <strong>milhojas de mousse de chocolate<\/strong> <strong>con guindas y crema de almendras<\/strong>. Las posibilidades son infinitas y los sabores \u00fanicos y deliciosos, solo es necesario saborearlas en alguna <a href=\"https:\/\/casaisabel.es\/it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>arrocer\u00eda o restaurante de la Malvarrosa<\/strong><\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.resuelto.com\/wp-content\/uploads\/2014\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0.jpg\" target=\"_blank\" rel=\"noopener noreferrer\">Imagen<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Una mousse es un irresistible postre de origen franc\u00e9s que se puede tomar, tanto salado como dulce, pero siempre bien fr\u00edo. La m\u00e1s conocida y deliciosa es la de chocolate, que pudo ser creada a finales del XIX por el pintor postimpresionista Toulouse-Lautrec, que frecuentaba las tabernas de Montmartre. Otras teor\u00edas sit\u00faan su autor\u00eda en [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo preparar una mousse valenciana - Casa Isabel<\/title>\n<meta name=\"description\" content=\"Descubre como preparar una buena mousse valenciana. Los pasos para hacer que su textura y sabor sean del agrado de todos los comensales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/it\/como-preparar-una-buena-mousse-en-valencia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo preparar una mousse valenciana - Casa Isabel\" \/>\n<meta property=\"og:description\" content=\"Descubre como preparar una buena mousse valenciana. Los pasos para hacer que su textura y sabor sean del agrado de todos los comensales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/it\/como-preparar-una-buena-mousse-en-valencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-26T00:17:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1814\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"C\u00f3mo preparar una mousse valenciana\",\"datePublished\":\"2026-01-26T00:17:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/\"},\"wordCount\":344,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg\",\"articleSection\":[\"Gastronom\u00eda\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/\",\"url\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/\",\"name\":\"C\u00f3mo preparar una mousse valenciana - Casa Isabel\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg\",\"datePublished\":\"2026-01-26T00:17:18+00:00\",\"description\":\"Descubre como preparar una buena mousse valenciana. Los pasos para hacer que su textura y sabor sean del agrado de todos los comensales\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg\",\"width\":2560,\"height\":1814,\"caption\":\"mousse de chocolate\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo preparar una mousse valenciana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/it\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo preparar una mousse valenciana - Casa Isabel","description":"Descubre como preparar una buena mousse valenciana. Los pasos para hacer que su textura y sabor sean del agrado de todos los comensales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/it\/como-preparar-una-buena-mousse-en-valencia\/","og_locale":"it_IT","og_type":"article","og_title":"C\u00f3mo preparar una mousse valenciana - Casa Isabel","og_description":"Descubre como preparar una buena mousse valenciana. Los pasos para hacer que su textura y sabor sean del agrado de todos los comensales","og_url":"https:\/\/casaisabel.es\/it\/como-preparar-una-buena-mousse-en-valencia\/","og_site_name":"Casa Isabel","article_published_time":"2026-01-26T00:17:18+00:00","og_image":[{"width":2560,"height":1814,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"C\u00f3mo preparar una mousse valenciana","datePublished":"2026-01-26T00:17:18+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/"},"wordCount":344,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg","articleSection":["Gastronom\u00eda"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/","url":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/","name":"C\u00f3mo preparar una mousse valenciana - Casa Isabel","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg","datePublished":"2026-01-26T00:17:18+00:00","description":"Descubre como preparar una buena mousse valenciana. Los pasos para hacer que su textura y sabor sean del agrado de todos los comensales","breadcrumb":{"@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/04\/Mousse_de_Chocolate_Chocolate_Blanco_0000x0000_0-scaled.jpg","width":2560,"height":1814,"caption":"mousse de chocolate"},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/como-preparar-una-buena-mousse-en-valencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo preparar una mousse valenciana"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/it\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts\/2467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/comments?post=2467"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts\/2467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/media\/2471"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/media?parent=2467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/categories?post=2467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/tags?post=2467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}