{"id":2077,"date":"2025-12-25T00:07:58","date_gmt":"2025-12-25T00:07:58","guid":{"rendered":"https:\/\/casaisabel.es\/?p=2077---8d128ff1-6079-4f1c-b063-f83cadd75078"},"modified":"2025-12-25T00:07:58","modified_gmt":"2025-12-25T00:07:58","slug":"la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/it\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/","title":{"rendered":"La Plaza Redonda de Valencia, un lugar emblem\u00e1tico y singular"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>En <a href=\"https:\/\/casaisabel.es\/it\/contacto\/\" target=\"_blank\" rel=\"noopener noreferrer\">Valencia<\/a> se pueden visitar innumerables lugares durante todo el a\u00f1o<\/strong>. Su playa, su conjunto hist\u00f3rico y monumental, adem\u00e1s de otra serie de rincones emblem\u00e1ticos y populares, hacen de esta ciudad un destino de gran atractivo tur\u00edstico.<!--more--><\/p>\n<p style=\"text-align: justify\"><strong>Desde su origen la Plaza Redonda funciona como mercado<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>La Plaza Redonda de <a href=\"http:\/\/www.diariodelviajero.com\/espana\/la-plaza-redonda-de-valencia-bulliciosa-antes-y-ahora\" target=\"_blank\" rel=\"noopener noreferrer\">Valencia<\/a> es, sin duda, una visita obligada para cualquier viajero por tratarse de un sitio pintoresco y acogedor.<\/strong> Obra de Salvador Escrig, la Plaza Nueva o del Cid, como se llamaba anteriormente, se construy\u00f3 en 1840. <strong>Se accede por cuatro calles que confluyen en un espacio luminoso y de construcci\u00f3n singular.<\/strong> Como su nombre indica, <strong>posee una planta circular, una fuente en el centro y se halla rodeada por una serie de viviendas.<\/strong> Desde all\u00ed, se puede contemplar el campanario de Santa Catalina y una cita, en el suelo, del autor valenciano Vicente Blasco Ib\u00e1\u00f1ez.<\/p>\n<p style=\"text-align: justify\"><strong>Desde su origen, esta plaza funciona como mercado<\/strong>. En los bajos de las casas, junto con otra serie de puestos en el anillo interior, se vend\u00edan comestibles, as\u00ed como art\u00edculos dom\u00e9sticos y textiles. En la actualidad, <strong>algunos de estos peque\u00f1os comercios conservan la tradici\u00f3n<\/strong>, aunque otros se han especializado en la venta de ropa y recuerdos de Valencia o se han transformado en bares de tapas. Los domingos, el bullicioso ambiente de la plaza adquiere mayor colorido con la llegada de otros comerciantes de cuadros, antig\u00fcedades y aves.\u00a0En el a\u00f1o 2012 se remodelaron las fachadas y los tejados de los edificios y se coloc\u00f3 una cubierta para resguardar a vendedores, compradores y mercanc\u00edas de la lluvia y el fr\u00edo.<\/p>\n<p style=\"text-align: justify\"><strong>Una vez que se recorre todo el mercadillo y se visitan los comercios tradicionales de la Plaza Redonda de Valencia, llega el momento de saborear una buena paella en una <a href=\"https:\/\/casaisabel.es\/it\/arroz-en-valencia\/\" target=\"_blank\" rel=\"noopener noreferrer\">arrocer\u00eda<\/a> o en un buen restaurante de la <a href=\"http:\/\/www.diariodelviajero.com\/espana\/la-plaza-redonda-de-valencia-bulliciosa-antes-y-ahora\" target=\"_blank\" rel=\"noopener noreferrer\">playa<\/a> de la Malvarrosa<\/strong>. Una visita a la capital del Turia resulta completa cuando se disfruta de su oferta gastron\u00f3mica y cultural a partes iguales.<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.flickr.com\/photos\/doublebug\/8174909660\/in\/photolist-dsoxQh-7NVWGa-a7nJMT-9pNtnQ-9pNtrm-4TH2g2-LHZHg-uwZ9n-8tc7zt-8tc86v-8tf7Vb-LJ1iM-bukYjj-bHfLEt-jBc684-6KdGT9-d3fe3f-911NTT-bukYgb--49PPXR-32iUF1-9qqGHf-gepAAL-34j3Zx-jeHfJu-bHfLS4-bHfLJz-bukYDC-bukYwo-bukYsA-bHfLZp-bHfLQ2-bukYbL-bukYBd-bukYu9-bukYFA-bukYkW-8JRFkw-342gXN-34xP8K-n1YUYE-33Ar6R-33AHsi-5A6sA9-d5Hj1s-96kYTt-34Cvj3-bktxE7-byouA8\" target=\"_blank\" rel=\"noopener noreferrer\">Imagen.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>En Valencia se pueden visitar innumerables lugares durante todo el a\u00f1o. Su playa, su conjunto hist\u00f3rico y monumental, adem\u00e1s de otra serie de rincones emblem\u00e1ticos y populares, hacen de esta ciudad un destino de gran atractivo tur\u00edstico.<\/p>","protected":false},"author":2,"featured_media":2079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-emblematicos-de-valencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Plaza Redonda de Valencia, tradici\u00f3n y comercio - Casa Isabel<\/title>\n<meta name=\"description\" content=\"La Plaza Redonda de Valencia es un lugar emblem\u00e1tico de la ciudad con una tradici\u00f3n comercial muy arraigada que todav\u00eda hoy d\u00eda se puede apreciar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/it\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Plaza Redonda de Valencia, tradici\u00f3n y comercio - Casa Isabel\" \/>\n<meta property=\"og:description\" content=\"La Plaza Redonda de Valencia es un lugar emblem\u00e1tico de la ciudad con una tradici\u00f3n comercial muy arraigada que todav\u00eda hoy d\u00eda se puede apreciar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/it\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-25T00:07:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"La Plaza Redonda de Valencia, un lugar emblem\u00e1tico y singular\",\"datePublished\":\"2025-12-25T00:07:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/\"},\"wordCount\":356,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png\",\"articleSection\":[\"Lugares emblem\u00e1ticos de Valencia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/\",\"url\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/\",\"name\":\"La Plaza Redonda de Valencia, tradici\u00f3n y comercio - Casa Isabel\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png\",\"datePublished\":\"2025-12-25T00:07:58+00:00\",\"description\":\"La Plaza Redonda de Valencia es un lugar emblem\u00e1tico de la ciudad con una tradici\u00f3n comercial muy arraigada que todav\u00eda hoy d\u00eda se puede apreciar.\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png\",\"width\":626,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Plaza Redonda de Valencia, un lugar emblem\u00e1tico y singular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/it\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Plaza Redonda de Valencia, tradici\u00f3n y comercio - Casa Isabel","description":"La Plaza Redonda de Valencia es un lugar emblem\u00e1tico de la ciudad con una tradici\u00f3n comercial muy arraigada que todav\u00eda hoy d\u00eda se puede apreciar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/it\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/","og_locale":"it_IT","og_type":"article","og_title":"La Plaza Redonda de Valencia, tradici\u00f3n y comercio - Casa Isabel","og_description":"La Plaza Redonda de Valencia es un lugar emblem\u00e1tico de la ciudad con una tradici\u00f3n comercial muy arraigada que todav\u00eda hoy d\u00eda se puede apreciar.","og_url":"https:\/\/casaisabel.es\/it\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/","og_site_name":"Casa Isabel","article_published_time":"2025-12-25T00:07:58+00:00","og_image":[{"width":626,"height":256,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png","type":"image\/png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"La Plaza Redonda de Valencia, un lugar emblem\u00e1tico y singular","datePublished":"2025-12-25T00:07:58+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/"},"wordCount":356,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png","articleSection":["Lugares emblem\u00e1ticos de Valencia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/","url":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/","name":"La Plaza Redonda de Valencia, tradici\u00f3n y comercio - Casa Isabel","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png","datePublished":"2025-12-25T00:07:58+00:00","description":"La Plaza Redonda de Valencia es un lugar emblem\u00e1tico de la ciudad con una tradici\u00f3n comercial muy arraigada que todav\u00eda hoy d\u00eda se puede apreciar.","breadcrumb":{"@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/11\/PlazaRedonda.png","width":626,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/la-plaza-redonda-de-valencia-un-lugar-emblematico-y-singular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"La Plaza Redonda de Valencia, un lugar emblem\u00e1tico y singular"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/it\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts\/2077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/comments?post=2077"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/posts\/2077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/media\/2079"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/media?parent=2077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/categories?post=2077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/it\/wp-json\/wp\/v2\/tags?post=2077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}