{"id":2425,"date":"2026-01-17T00:03:40","date_gmt":"2026-01-17T00:03:40","guid":{"rendered":"https:\/\/casaisabel.es\/?p=2425---2e6ca3f4-b796-44c9-9023-49b7aadd207d"},"modified":"2026-01-17T00:03:40","modified_gmt":"2026-01-17T00:03:40","slug":"el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/fr\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/","title":{"rendered":"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano"},"content":{"rendered":"<p style=\"text-align: justify\">Una ruta por <strong>la ciudad de Valencia es un viaje por <a href=\"https:\/\/casaisabel.es\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">su gastronom\u00eda<\/a>, su playa o sus festejos, pero tambi\u00e9n por su arte e historia.<\/strong> La ciudad est\u00e1 plagada de rincones que evocan \u00e9pocas doradas de arte, como ocurre con el Mercado de Col\u00f3n.<strong> Este emblem\u00e1tico edificio, situado en el Primer Ensanche, es un ejemplo del paso del modernismo por la ciudad.<\/strong> Una corriente <strong>caracterizada por el uso de hierro, cer\u00e1mica o vidrio, as\u00ed como elementos decorativos representativos de la zona, como las huertas, naranjas, falleras o pescadores.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify\"><strong>Un edificio que se construyo hace un siglo, pero que sigue vivo para los valencianos<\/strong><\/p>\n<p style=\"text-align: justify\">El Mercado fue <strong>construido en el a\u00f1o 1914 por el arquitecto municipal Francisco Mora<\/strong>, para abastecer la demanda creciente del vecindario. Para ello, se construye un gran espacio longitudinal de tres naves con cerchas met\u00e1licas y dos portadas de ladrillo y piedra cerrando sus extremos,<strong> a la manera de arcos triunfales, con policrom\u00eda y gran ornamentaci\u00f3n<\/strong>. El conjunto lo remata una verja art\u00edstica de forja que le da una imagen rectangular, con esquinas achaflanadas de 100&#215;47 metros. <strong>Su estilo estaba influido por las <a href=\"http:\/\/www.lovevalencia.com\/el-modernismo-en-valencia.html\" target=\"_blank\" rel=\"noopener noreferrer\">corrientes modernistas<\/a> catalanas de Dom\u00e8nech i Montaner y Puig i Cadafalch.<\/strong> El edificio fue inaugurado en la Nochebuena de 1916, entre una enorme expectaci\u00f3n de la sociedad de la \u00e9poca.<\/p>\n<p style=\"text-align: justify\">En la actualidad, <strong>la rehabilitaci\u00f3n le ha devuelto el brillo de la exquisita decoraci\u00f3n original,<\/strong> armoniz\u00e1ndolo con un proyecto vanguardista, compuesto por seis cubos de cristal que <strong>albergan tiendas, restaurantes, comercios y <a href=\"http:\/\/www.mercadocolon.es\/edificio.php\" target=\"_blank\" rel=\"noopener noreferrer\">el mercado<\/a>, donde los valencianos pueden relajarse y disfrutar<\/strong> del entorno.<\/p>\n<p style=\"text-align: justify\">Un recorrido por el arte modernista de la ciudad llevar\u00e1 al viajero, adem\u00e1s, a <a href=\"https:\/\/casaisabel.es\/fr\/blog\/\" target=\"_blank\" rel=\"noopener noreferrer\">emblem\u00e1ticos lugares<\/a>, como <strong>la Estaci\u00f3n del Norte o el Edificio de Correos, en el tradicional barrio de pescadores, testigos vivos del paso del modernismo por la ciudad<\/strong>. Para descansar del paseo, nada mejor que deleitarse con una paella en alguna arrocer\u00eda o restaurante en la Malvarrosa, todo un placer para los sentidos.<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.flickr.com\/photos\/on1stsite\/4655139679\/in\/photolist-86mNQX-oRQuf8-o9KcB1-p7htff-p7hGAo-p9jymk-pevTQh-qbrtsq-pU5oWz-qbjEVZ-pU4z2i-pU5vCa-pU5W9z-q1DN6S-pTWh45-qCWRbN-peJMR6-qCWLRC-pYuWhW-oc9khn-p946pa-oRQhB9-oRPNAm-oRPLtq-p7hCGG-oRPVWU-p945ha-oRPTiY-nSfniL-bk9H6y-by58m4-nSTAo6-6NbYgi-9D9GaK-oUWjjk-oc9iSP-o9rDWD-9D5BBc-9D5CU4-9D5DDX-9D5Ecc-nSSDnC-oaermu-57XLcg-nSSYmh-o9DYRQ-oahtXU-5FnEGL-5FnDLN-aFmjEc\" target=\"_blank\" rel=\"noopener noreferrer\">Imagen.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Una ruta por la ciudad de Valencia es un viaje por su gastronom\u00eda, su playa o sus festejos, pero tambi\u00e9n por su arte e historia. La ciudad est\u00e1 plagada de rincones que evocan \u00e9pocas doradas de arte, como ocurre con el Mercado de Col\u00f3n. Este emblem\u00e1tico edificio, situado en el Primer Ensanche, es un ejemplo [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-emblematicos-de-valencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano<\/title>\n<meta name=\"description\" content=\"Un edificio que se construyo hace un siglo, pero que sigue vivo para el pueblo de Valencia, siendo un referente del modernismo valenciano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/fr\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano\" \/>\n<meta property=\"og:description\" content=\"Un edificio que se construyo hace un siglo, pero que sigue vivo para el pueblo de Valencia, siendo un referente del modernismo valenciano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/fr\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-17T00:03:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1043\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano\",\"datePublished\":\"2026-01-17T00:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/\"},\"wordCount\":354,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg\",\"articleSection\":[\"Lugares emblem\u00e1ticos de Valencia\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/\",\"url\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/\",\"name\":\"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg\",\"datePublished\":\"2026-01-17T00:03:40+00:00\",\"description\":\"Un edificio que se construyo hace un siglo, pero que sigue vivo para el pueblo de Valencia, siendo un referente del modernismo valenciano.\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg\",\"width\":2560,\"height\":1043},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/fr\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano","description":"Un edificio que se construyo hace un siglo, pero que sigue vivo para el pueblo de Valencia, siendo un referente del modernismo valenciano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/fr\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/","og_locale":"fr_FR","og_type":"article","og_title":"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano","og_description":"Un edificio que se construyo hace un siglo, pero que sigue vivo para el pueblo de Valencia, siendo un referente del modernismo valenciano.","og_url":"https:\/\/casaisabel.es\/fr\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/","og_site_name":"Casa Isabel","article_published_time":"2026-01-17T00:03:40+00:00","og_image":[{"width":2560,"height":1043,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano","datePublished":"2026-01-17T00:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/"},"wordCount":354,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg","articleSection":["Lugares emblem\u00e1ticos de Valencia"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/","url":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/","name":"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg","datePublished":"2026-01-17T00:03:40+00:00","description":"Un edificio que se construyo hace un siglo, pero que sigue vivo para el pueblo de Valencia, siendo un referente del modernismo valenciano.","breadcrumb":{"@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/4655139679_a0d8b847ab_o-scaled.jpg","width":2560,"height":1043},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/el-mercado-de-colon-un-simbolo-del-modernismo-en-valencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"El Mercado de Col\u00f3n, un s\u00edmbolo del modernismo valenciano"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/fr\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/posts\/2425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/comments?post=2425"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/posts\/2425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/media\/2429"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/media?parent=2425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/categories?post=2425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/tags?post=2425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}