{"id":2386,"date":"2026-01-19T00:08:03","date_gmt":"2026-01-19T00:08:03","guid":{"rendered":"https:\/\/casaisabel.es\/?p=2386---ffa552cf-902e-4024-a608-9d106a0acbf8"},"modified":"2026-01-19T00:08:03","modified_gmt":"2026-01-19T00:08:03","slug":"la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/fr\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/","title":{"rendered":"La Nit del Foc: la gran noche de la pirotecnia en Valencia"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Entre los d\u00edas 15 y 19 de marzo se celebran las Fallas de Valencia, uno de los acontecimientos festivos m\u00e1s importantes de Espa\u00f1a<\/strong>. Con una repercusi\u00f3n que trasciende el \u00e1mbito de las fronteras espa\u00f1olas, la ciudad se convierte durante estos d\u00edas en un importante foco de atracci\u00f3n tur\u00edstica. Una gran multitud de visitantes se acerca hasta ella cada a\u00f1o, con la intenci\u00f3n de <strong>perderse entre sus calles, contemplar las fallas, disfrutar de los diferentes espect\u00e1culos y, c\u00f3mo no, <a href=\"https:\/\/casaisabel.es\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">probar una paella<\/a> u otras especialidades<\/strong> de la cocina local.<!--more--><\/p>\n<p style=\"text-align: justify\"><strong>Fuego, p\u00f3lvora y colores que cuentan la tradici\u00f3n y la pasi\u00f3n valenciana.<\/strong><\/p>\n<p style=\"text-align: justify\">Las Fallas son unas fiestas donde <strong>el fuego y la p\u00f3lvora adquieren un protagonismo especial mediante la quema de fallas, masclet\u00e1s y castillos de fuegos artificiales<\/strong>. <a href=\"http:\/\/www.vivirvalencia.com\/fallas-valencia\/nit-del-foc\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>La <em>Nit del Foc<\/em><\/strong><\/a> (Noche del Fuego) <strong>es el mayor y m\u00e1s multitudinario espect\u00e1culo pirot\u00e9cnico<\/strong> de las fiestas josefinas. Su celebraci\u00f3n tiene lugar en <a href=\"http:\/\/www.lovevalencia.com\/evento\/nit-del-foc-2015\" target=\"_blank\" rel=\"noopener noreferrer\">la noche del 18<\/a> al 19 de marzo, d\u00eda de San Jos\u00e9, y consiste en la quema de un espectacular castillo de fuegos artificiales que <strong>congrega anualmente a m\u00e1s de 500.000 personas<\/strong>. Se trata, sin duda, de uno de los actos m\u00e1s multitudinarios de las Fallas.<\/p>\n<p style=\"text-align: justify\"><strong>Con una duraci\u00f3n media de 20 minutos<\/strong>, en la Nit del Foc <strong>se llegan a quemar unos 4.000 kilos de material explosivo<\/strong> que alumbra la noche valenciana, haci\u00e9ndose visible desde m\u00faltiples puntos de la ciudad. El cielo se ilumina con multitud de colores, <strong>mientras la pirotecnia dibuja sobre las cabezas de los asistentes infinidad de formas y figuras<\/strong> en un espect\u00e1culo sin parang\u00f3n. La Nit del Foc tiene lugar de madrugada y <strong>es disparada desde el cauce viejo del Turia<\/strong>, a la altura del puente de Las Flores.<\/p>\n<p style=\"text-align: justify\">Se trata de una raz\u00f3n m\u00e1s para visitar Valencia durante sus fiestas mayores. <strong>Una ocasi\u00f3n que puede completarse disfrutando de su <a href=\"https:\/\/casaisabel.es\/fr\/restaurants-plage-malvarrosa\/\" target=\"_blank\" rel=\"noopener noreferrer\">gastronom\u00eda<\/a><\/strong>, ya sea en el centro o en la playa, visitando alguna arrocer\u00eda o un restaurante en Malvarrosa.<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.flickr.com\/photos\/carquinyol\/2344701533\" target=\"_blank\" rel=\"noopener noreferrer\">Imagen<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Entre los d\u00edas 15 y 19 de marzo se celebran las Fallas de Valencia, uno de los acontecimientos festivos m\u00e1s importantes de Espa\u00f1a. Con una repercusi\u00f3n que trasciende el \u00e1mbito de las fronteras espa\u00f1olas, la ciudad se convierte durante estos d\u00edas en un importante foco de atracci\u00f3n tur\u00edstica. Una gran multitud de visitantes se acerca [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-eventos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Nit del Foc: la gran noche de la pirotecnia en Valencia<\/title>\n<meta name=\"description\" content=\"El fuego y la pirotecnia son los protagonistas de la \u00faltima noche de las fiestas mayores de Valencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/fr\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Nit del Foc: la gran noche de la pirotecnia en Valencia\" \/>\n<meta property=\"og:description\" content=\"El fuego y la pirotecnia son los protagonistas de la \u00faltima noche de las fiestas mayores de Valencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/fr\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T00:08:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"La Nit del Foc: la gran noche de la pirotecnia en Valencia\",\"datePublished\":\"2026-01-19T00:08:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/\"},\"wordCount\":363,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg\",\"articleSection\":[\"Actualidad y eventos\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/\",\"url\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/\",\"name\":\"La Nit del Foc: la gran noche de la pirotecnia en Valencia\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg\",\"datePublished\":\"2026-01-19T00:08:03+00:00\",\"description\":\"El fuego y la pirotecnia son los protagonistas de la \u00faltima noche de las fiestas mayores de Valencia.\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg\",\"width\":1024,\"height\":417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Nit del Foc: la gran noche de la pirotecnia en Valencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/fr\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Nit del Foc: la gran noche de la pirotecnia en Valencia","description":"El fuego y la pirotecnia son los protagonistas de la \u00faltima noche de las fiestas mayores de Valencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/fr\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/","og_locale":"fr_FR","og_type":"article","og_title":"La Nit del Foc: la gran noche de la pirotecnia en Valencia","og_description":"El fuego y la pirotecnia son los protagonistas de la \u00faltima noche de las fiestas mayores de Valencia.","og_url":"https:\/\/casaisabel.es\/fr\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/","og_site_name":"Casa Isabel","article_published_time":"2026-01-19T00:08:03+00:00","og_image":[{"width":1024,"height":417,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"La Nit del Foc: la gran noche de la pirotecnia en Valencia","datePublished":"2026-01-19T00:08:03+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/"},"wordCount":363,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg","articleSection":["Actualidad y eventos"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/","url":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/","name":"La Nit del Foc: la gran noche de la pirotecnia en Valencia","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg","datePublished":"2026-01-19T00:08:03+00:00","description":"El fuego y la pirotecnia son los protagonistas de la \u00faltima noche de las fiestas mayores de Valencia.","breadcrumb":{"@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/03\/nit_del_focddd.jpg","width":1024,"height":417},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/la-nit-del-foc-la-gran-noche-de-la-pirotecnia-en-valencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"La Nit del Foc: la gran noche de la pirotecnia en Valencia"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/fr\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/posts\/2386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/comments?post=2386"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/posts\/2386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/media\/2387"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/media?parent=2386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/categories?post=2386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/fr\/wp-json\/wp\/v2\/tags?post=2386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}