{"id":2762,"date":"2025-08-08T00:07:27","date_gmt":"2025-08-08T00:07:27","guid":{"rendered":"https:\/\/casaisabel.es\/?p=2762---5a3156a3-9e6e-48fb-a5f8-fbf438807adb"},"modified":"2025-08-08T00:07:27","modified_gmt":"2025-08-08T00:07:27","slug":"embutido-de-requena-gastronomia-y-tradicion","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/en\/embutido-de-requena-gastronomia-y-tradicion\/","title":{"rendered":"Embutido de Requena, gastronom\u00eda y tradici\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Valencia<\/strong> es una tierra rica en <strong>productos frescos y de calidad<\/strong>, sus famosas huertas abastecen a la regi\u00f3n con hortalizas y frutas de un sabor y aroma \u00fanicos y su rica <strong>paella<\/strong>, elaborada con el mejor <strong>arroz<\/strong>, es conocida y degustada en el mundo entero. Pero en carnes, esta bella regi\u00f3n no se queda atr\u00e1s, el famoso <strong>Embutido de Requena<\/strong>, elaborado con las mejores materias primas, un clima favorable y siguiendo la tradici\u00f3n, es uno de sus productos m\u00e1s deliciosos.<!--more--><\/p>\n<p style=\"text-align: justify;\">En un enclave privilegiado<strong> entre monta\u00f1as, almendros, vi\u00f1edos y proximidad a la playa<\/strong>, se cr\u00edan los cerdos cuya carne posteriormente servir\u00e1 para preparar los tradicionales <strong>productos de Requena<\/strong>, como la <strong>longaniza<\/strong>, el <strong>chorizo<\/strong>, la <strong>sobrasada<\/strong>, la <strong>morcilla de cebolla<\/strong>, el <strong>salchich\u00f3n<\/strong>, el <strong>perro<\/strong>, la <strong>g\u00fce\u00f1a<\/strong>&#8230; Gracias a unas <strong>condiciones clim\u00e1ticas id\u00f3neas<\/strong>, de tipo semicontinental, con una d\u00e9bil influencia de la costa, es posible el secado y oreo de tan sabrosos productos de la tierra, elaborados siguiendo <strong>procesos tradicionales<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, la <strong>gastronom\u00eda de Requena<\/strong> es conocida por <strong>fuertes y deliciosos platos<\/strong> como son la <strong>olla de bajocas<\/strong>, un guiso a base de jud\u00edas, verduras y derivados del cerdo, as\u00ed como el <strong>arroz en cazuela<\/strong>, el <strong>morteruelo<\/strong>, el <strong>cachul\u00ed<\/strong> y otros de tradici\u00f3n castellana como la <strong>gachamiga<\/strong>, el <strong>ajoarriero<\/strong> o el <strong>gazpacho manchego<\/strong>. Se pueden a\u00f1adir tambi\u00e9n sus ricos postres como el <strong>alaj\u00fa<\/strong> o las <strong>gachas<\/strong>.<\/p>\n<p style=\"text-align: justify;\">El orgullo que siente este pueblo por sus ricos platos se aprecia en las numerosas <strong>ferias gastron\u00f3micas<\/strong> de embutidos artesanos, donde locales y visitantes pueden degustar sus <strong>\u00absiete magn\u00edficos requeneses\u00bb<\/strong> y acompa\u00f1arlos con los <strong>caldos D.O. Utiel-Requena<\/strong>, de una gran calidad.<\/p>\n<p style=\"text-align: justify;\">Conocer y vivir esta comunidad es un placer para cualquiera que se acerca a Valencia. As\u00ed como disfrutar de sus pueblos, ricos en gastronom\u00eda y tradiciones o de su capital, una bella ciudad donde saborear el mar desde una <strong>arrocer\u00eda o <a href=\"https:\/\/casaisabel.es\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\">restaurante en la Malvarrosa<\/a><\/strong>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.flickr.com\/photos\/jlastras\/4592670286\/in\/photolist-7ZQCSs-9m69vM-mMZsVn-5rzPHR-5rE8aG-oU3X5B-oU4ZH9-oU3X2R-oU3WYz-oU3WZM-pbwiLE-oU3WWv-p9wfME-pbyjQ2-pbwiD5-p9wfGj-pbheQv-pbxYpc-pbvXrb-pbvXn3-p9vUvh-pbvXiA-bt2WJD-bt2WNn-amvMSi-bt2Wzc-bt2ZKK-bt2\" target=\"_blank\" rel=\"noopener noreferrer\">Imagen<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Valencia es una tierra rica en productos frescos y de calidad, sus famosas huertas abastecen a la regi\u00f3n con hortalizas y frutas de un sabor y aroma \u00fanicos y su rica paella, elaborada con el mejor arroz, es conocida y degustada en el mundo entero. Pero en carnes, esta bella regi\u00f3n no se queda atr\u00e1s, [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[27],"class_list":["post-2762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-d-o-valencia-y-tipos-vino","tag-embutido-de-requena"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Embutido de Requena, gastronom\u00eda y tradici\u00f3n - Casa Isabel<\/title>\n<meta name=\"description\" content=\"Pero en carnes, esta bella regi\u00f3n no se queda atr\u00e1s, el famoso Embutido de Requena, elaborado con las mejores materias primas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/en\/embutido-de-requena-gastronomia-y-tradicion\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embutido de Requena, gastronom\u00eda y tradici\u00f3n - Casa Isabel\" \/>\n<meta property=\"og:description\" content=\"Pero en carnes, esta bella regi\u00f3n no se queda atr\u00e1s, el famoso Embutido de Requena, elaborado con las mejores materias primas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/en\/embutido-de-requena-gastronomia-y-tradicion\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-08T00:07:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"353\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"Embutido de Requena, gastronom\u00eda y tradici\u00f3n\",\"datePublished\":\"2025-08-08T00:07:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/\"},\"wordCount\":345,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg\",\"keywords\":[\"embutido de requena\"],\"articleSection\":[\"D.O. Valencia y tipos vino\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/\",\"url\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/\",\"name\":\"Embutido de Requena, gastronom\u00eda y tradici\u00f3n - Casa Isabel\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg\",\"datePublished\":\"2025-08-08T00:07:27+00:00\",\"description\":\"Pero en carnes, esta bella regi\u00f3n no se queda atr\u00e1s, el famoso Embutido de Requena, elaborado con las mejores materias primas.\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg\",\"width\":1024,\"height\":353,\"caption\":\"cisabel_embutido\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embutido de Requena, gastronom\u00eda y tradici\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/en\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embutido de Requena, gastronom\u00eda y tradici\u00f3n - Casa Isabel","description":"Pero en carnes, esta bella regi\u00f3n no se queda atr\u00e1s, el famoso Embutido de Requena, elaborado con las mejores materias primas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/en\/embutido-de-requena-gastronomia-y-tradicion\/","og_locale":"en_GB","og_type":"article","og_title":"Embutido de Requena, gastronom\u00eda y tradici\u00f3n - Casa Isabel","og_description":"Pero en carnes, esta bella regi\u00f3n no se queda atr\u00e1s, el famoso Embutido de Requena, elaborado con las mejores materias primas.","og_url":"https:\/\/casaisabel.es\/en\/embutido-de-requena-gastronomia-y-tradicion\/","og_site_name":"Casa Isabel","article_published_time":"2025-08-08T00:07:27+00:00","og_image":[{"width":1024,"height":353,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"Embutido de Requena, gastronom\u00eda y tradici\u00f3n","datePublished":"2025-08-08T00:07:27+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/"},"wordCount":345,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg","keywords":["embutido de requena"],"articleSection":["D.O. Valencia y tipos vino"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/","url":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/","name":"Embutido de Requena, gastronom\u00eda y tradici\u00f3n - Casa Isabel","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg","datePublished":"2025-08-08T00:07:27+00:00","description":"Pero en carnes, esta bella regi\u00f3n no se queda atr\u00e1s, el famoso Embutido de Requena, elaborado con las mejores materias primas.","breadcrumb":{"@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/07\/cisabel_embutido.jpg","width":1024,"height":353,"caption":"cisabel_embutido"},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/embutido-de-requena-gastronomia-y-tradicion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"Embutido de Requena, gastronom\u00eda y tradici\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/en\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts\/2762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/comments?post=2762"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts\/2762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/media\/2763"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/media?parent=2762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/categories?post=2762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/tags?post=2762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}