{"id":2689,"date":"2026-02-02T00:07:20","date_gmt":"2026-02-02T00:07:20","guid":{"rendered":"https:\/\/casaisabel.es\/?p=2689---09f02836-9a2b-41a1-a63b-3d49242b76dd"},"modified":"2026-02-02T00:07:20","modified_gmt":"2026-02-02T00:07:20","slug":"agua-de-valencia-un-coctel-delicioso-y-refrescante","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/en\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/","title":{"rendered":"Agua de Valencia, un c\u00f3ctel delicioso y refrescante"},"content":{"rendered":"<p style=\"text-align: justify;\">Llega el <strong>verano<\/strong> y con \u00e9l los c\u00e1lidos d\u00edas de <strong>sol y playa<\/strong>, momentos ideales para desconectar de las obligaciones y rutinas y disfrutar del ocio y la <strong>gastronom\u00eda de Valencia<\/strong>. Una magn\u00edfica forma de hacerlo es saboreando uno de sus m\u00e1s refrescantes productos, el<strong> Agua de Valencia<\/strong>, un gran aliado contra el calor del que disfrutar en alguna terraza o <a href=\"https:\/\/casaisabel.es\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>restaurante en la Malvarrosa<\/strong><\/a>.<!--more--><\/p>\n<p style=\"text-align: justify;\">Este delicioso c\u00f3ctel, ya presente en las mesas valencianas desde <strong>finales de los 50<\/strong>, es a d\u00eda de hoy, muy consumido y valorado por valencianos y visitantes. Se realiza con <strong>zumo de naranja, vodka, ginebra y champ\u00e1n o cava<\/strong> y su elaboraci\u00f3n es muy sencilla. En una copa se a\u00f1ade zumo de naranja reci\u00e9n exprimido y champ\u00e1n a partes iguales y la mitad de vodka y ginebra; despu\u00e9s, se a\u00f1ade az\u00facar al gusto, se remueve todo y se sirve muy fr\u00edo. Existen adem\u00e1s otras variedades con ron o sidra, as\u00ed como versiones de distintas ciudades y zonas de todo el mundo como el Agua de Sevilla o el<strong> Agua de Malvarrosa<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan narra la escritora <strong>Mar\u00eda \u00c1ngeles Arazo<\/strong> en su obra <strong>\u00abValencia noche\u00bb<\/strong>, su origen proviene de la <strong>Cervecer\u00eda Madrid<\/strong>, donde un grupo de viajantes de procedencia vasca ped\u00eda siempre <strong>\u00abAgua de Bilbao\u00bb<\/strong>, en referencia al mejor espumoso del local, pero en una ocasi\u00f3n, ya cansados de tomarlo, retaron al due\u00f1o del bar, <strong>Constante Gil<\/strong>, a que elaborara algo novedoso y les ofreci\u00f3 <a href=\"http:\/\/www.aguadevalencia.net\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>\u00abAgua de Valencia\u00bb<\/strong><\/a>. Su delicioso sabor hizo que en sucesivas ocasiones solo pidieran este c\u00f3ctel, aunque ser\u00eda ya en la <strong>d\u00e9cada de los 70<\/strong> cuando se abri\u00f3 al gran p\u00fablico para hacerse muy conocido y demandado en las c\u00e1lidas noches valencianas.<\/p>\n<p style=\"text-align: justify;\">Disfrutar de una deliciosa <strong>paella en una arrocer\u00eda del Paseo Mar\u00edtimo<\/strong>, para saborear despu\u00e9s este refrescante c\u00f3ctel en la mejor compa\u00f1\u00eda, es un verdadero placer para los sentidos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/agualuna.es\/wp-content\/uploads\/2015\/06\/jarra-agua-de-valencia.jpg\" target=\"_blank\" rel=\"noopener noreferrer\">Fuente de imagen<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Llega el verano y con \u00e9l los c\u00e1lidos d\u00edas de sol y playa, momentos ideales para desconectar de las obligaciones y rutinas y disfrutar del ocio y la gastronom\u00eda de Valencia. Una magn\u00edfica forma de hacerlo es saboreando uno de sus m\u00e1s refrescantes productos, el Agua de Valencia, un gran aliado contra el calor del [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agua de Valencia, un c\u00f3ctel delicioso y refrescante - Casa Isabel<\/title>\n<meta name=\"description\" content=\"El Agua de Valencia, un gran aliado contra el calor del que disfrutar en alguna terraza o restaurante en la Malvarrosa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/en\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agua de Valencia, un c\u00f3ctel delicioso y refrescante - Casa Isabel\" \/>\n<meta property=\"og:description\" content=\"El Agua de Valencia, un gran aliado contra el calor del que disfrutar en alguna terraza o restaurante en la Malvarrosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/en\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T00:07:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"629\" \/>\n\t<meta property=\"og:image:height\" content=\"217\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"Agua de Valencia, un c\u00f3ctel delicioso y refrescante\",\"datePublished\":\"2026-02-02T00:07:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/\"},\"wordCount\":350,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg\",\"articleSection\":[\"Gastronom\u00eda\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/\",\"url\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/\",\"name\":\"Agua de Valencia, un c\u00f3ctel delicioso y refrescante - Casa Isabel\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg\",\"datePublished\":\"2026-02-02T00:07:20+00:00\",\"description\":\"El Agua de Valencia, un gran aliado contra el calor del que disfrutar en alguna terraza o restaurante en la Malvarrosa.\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg\",\"width\":629,\"height\":217,\"caption\":\"cisabel_agua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agua de Valencia, un c\u00f3ctel delicioso y refrescante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/en\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agua de Valencia, un c\u00f3ctel delicioso y refrescante - Casa Isabel","description":"El Agua de Valencia, un gran aliado contra el calor del que disfrutar en alguna terraza o restaurante en la Malvarrosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/en\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/","og_locale":"en_GB","og_type":"article","og_title":"Agua de Valencia, un c\u00f3ctel delicioso y refrescante - Casa Isabel","og_description":"El Agua de Valencia, un gran aliado contra el calor del que disfrutar en alguna terraza o restaurante en la Malvarrosa.","og_url":"https:\/\/casaisabel.es\/en\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/","og_site_name":"Casa Isabel","article_published_time":"2026-02-02T00:07:20+00:00","og_image":[{"width":629,"height":217,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"Agua de Valencia, un c\u00f3ctel delicioso y refrescante","datePublished":"2026-02-02T00:07:20+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/"},"wordCount":350,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg","articleSection":["Gastronom\u00eda"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/","url":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/","name":"Agua de Valencia, un c\u00f3ctel delicioso y refrescante - Casa Isabel","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg","datePublished":"2026-02-02T00:07:20+00:00","description":"El Agua de Valencia, un gran aliado contra el calor del que disfrutar en alguna terraza o restaurante en la Malvarrosa.","breadcrumb":{"@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2015\/06\/cisabel_agua.jpg","width":629,"height":217,"caption":"cisabel_agua"},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/agua-de-valencia-un-coctel-delicioso-y-refrescante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"Agua de Valencia, un c\u00f3ctel delicioso y refrescante"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/en\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts\/2689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/comments?post=2689"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts\/2689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/media\/2690"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/media?parent=2689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/categories?post=2689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/tags?post=2689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}