{"id":1533,"date":"2025-12-01T00:09:18","date_gmt":"2025-12-01T00:09:18","guid":{"rendered":"https:\/\/casaisabel.es\/?p=1533---a3e7b056-28ac-4f53-929c-d30b8e1426c1"},"modified":"2025-12-01T00:09:18","modified_gmt":"2025-12-01T00:09:18","slug":"el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea","status":"publish","type":"post","link":"https:\/\/casaisabel.es\/en\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/","title":{"rendered":"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea"},"content":{"rendered":"<p>Aceite de oliva, carnes, pescados y verduras son algunos de los\u00a0<strong>ingredientes<\/strong>\u00a0que conforman la gastronom\u00eda\u00a0<a href=\"http:\/\/es.wikipedia.org\/wiki\/Dieta_mediterr%C3%A1nea\" target=\"_blank\" rel=\"noopener noreferrer\">mediterr\u00e1nea<\/a>, basada en h\u00e1bitos alimenticios presentes tanto en Espa\u00f1a como en Francia, Italia o Grecia.<!--more--><\/p>\n<p>Sin duda, uno de los integrantes\u00a0<strong>primordiales<\/strong>\u00a0de esta dieta -declarada Patrimonio Cultural Inmaterial de la Humanidad en 2010 y con propiedades saludables cient\u00edficamente contrastadas- es el cereal, particularmente el arroz.<\/p>\n<p>En el caso espa\u00f1ol, Valencia es\u00a0<strong>patria<\/strong>\u00a0indiscutible de arroces -cuya introducci\u00f3n se atribuye al pueblo \u00e1rabe en el siglo VIII- y la paella es el sabroso s\u00edmbolo que ha llevado el nombre de la comunidad por todo el mundo. Ya sean nativos o turistas, la playa es la ubicaci\u00f3n escogida por muchos para degustar una paella valenciana en uno de los numerosos restaurantes repartidos por la Malvarrosa, en la que la\u00a0<strong>mejor<\/strong>\u00a0opci\u00f3n es Casa Isabel.<\/p>\n<p>Los datos hablan por s\u00ed solos. Con 921,7 miles de toneladas de producci\u00f3n anual en Espa\u00f1a, la superficie dedicada en Valencia al cultivo del arroz\u00a0<strong>convierte<\/strong>\u00a0a este cereal en el segundo m\u00e1s importante\u00a0de la comunidad\u00a0\u2013\u00fanicamente por debajo de la cebada- \u00a0al ocupar 17.130 hect\u00e1reas.<\/p>\n<p>Aunque el cultivo de este cereal estuvo acompa\u00f1ado, hist\u00f3ricamente, de conflictos que llegaron a culminar en la declaraci\u00f3n de su cosecha como perjudicial, en el siglo XIX se produjo una notable\u00a0<strong>expansi\u00f3n<\/strong>\u00a0de la superficie dedicada a este proceso y hoy conforma la base agr\u00edcola principal, por ejemplo, en la zona de la Albufera.<\/p>\n<p>Tres de sus variedades \u2013senia, bomba y albufera- est\u00e1n amparadas por la Denominaci\u00f3n de Origen Arroz de Valencia y son muy\u00a0<strong>apreciadas<\/strong>\u00a0en las cocinas del todo el mundo. Entre sus cualidades destaca su capacidad de conducci\u00f3n de sabores o la respuesta uniforme de cocci\u00f3n que presentan sus granos. As\u00ed, el arroz\u00a0<strong>ocupa<\/strong>\u00a0uno de los tronos de la gastronom\u00eda mediterr\u00e1nea. Su sabor y sus propiedades son las principales ra\u00edces que nutren esta corona.<\/p>\n<p><a href=\"https:\/\/www.flickr.com\/photos\/robinhoypaco\/4434453689\/in\/photolist-7KRJA6-csDPKA-m7dY47-8xSoqs-4PozPq-mw3kCC-m7d5X8-dRW8Hq-oAjBHv-m7d3uc-m7efQ3-m7e8Jj-m7cZfD-m7eKBG-m7dQwH-49pj5q-dhBf5w-m7dC3V-m7d8Ja-6T96jb-m7eQL9-m7ebQ8-m7cMQz-m7dvWt-m7d9he-m7eanQ-m7eVr1-m7fd7L-m7dg7X-m7fazw-m7dPWe-m7dUTZ-m7eB99-m7e3vH-m7dBza-m7eG3Y-m7eXcA-m7fdpj-m7dHWP-m7diRe-m7ee8z-m7eeDK-m7cSFX-m7dsEB-m7euHd-m7etNN-m7efu3-m7dpTp-m7dBok-m7edQm\" target=\"_blank\" rel=\"noopener noreferrer\">Imagen<\/a>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Aceite de oliva, carnes, pescados y verduras son algunos de los\u00a0ingredientes\u00a0que conforman la gastronom\u00eda\u00a0mediterr\u00e1nea, basada en h\u00e1bitos alimenticios presentes tanto en Espa\u00f1a como en Francia, Italia o Grecia.<\/p>","protected":false},"author":2,"featured_media":1534,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea<\/title>\n<meta name=\"description\" content=\"CASA ISABEL. Restaurante en Valencia. Disfruta de una exquisita comida mediterranea en la costa de la ciudad de uno de los mejores restaurantes de Valencia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/en\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea\" \/>\n<meta property=\"og:description\" content=\"CASA ISABEL. Restaurante en Valencia. Disfruta de una exquisita comida mediterranea en la costa de la ciudad de uno de los mejores restaurantes de Valencia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/en\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T00:09:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"257\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\"},\"headline\":\"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea\",\"datePublished\":\"2025-12-01T00:09:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/\"},\"wordCount\":351,\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png\",\"articleSection\":[\"Gastronom\u00eda\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/\",\"url\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/\",\"name\":\"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png\",\"datePublished\":\"2025-12-01T00:09:18+00:00\",\"description\":\"CASA ISABEL. Restaurante en Valencia. Disfruta de una exquisita comida mediterranea en la costa de la ciudad de uno de los mejores restaurantes de Valencia\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png\",\"width\":640,\"height\":257},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/casaisabel.es\/en\/author\/admin-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea","description":"CASA ISABEL. Restaurante en Valencia. Disfruta de una exquisita comida mediterranea en la costa de la ciudad de uno de los mejores restaurantes de Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/en\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/","og_locale":"en_GB","og_type":"article","og_title":"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea","og_description":"CASA ISABEL. Restaurante en Valencia. Disfruta de una exquisita comida mediterranea en la costa de la ciudad de uno de los mejores restaurantes de Valencia","og_url":"https:\/\/casaisabel.es\/en\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/","og_site_name":"Casa Isabel","article_published_time":"2025-12-01T00:09:18+00:00","og_image":[{"width":640,"height":257,"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png","type":"image\/png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#article","isPartOf":{"@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/"},"author":{"name":"Admin","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf"},"headline":"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea","datePublished":"2025-12-01T00:09:18+00:00","mainEntityOfPage":{"@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/"},"wordCount":351,"publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"image":{"@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png","articleSection":["Gastronom\u00eda"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/","url":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/","name":"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png","datePublished":"2025-12-01T00:09:18+00:00","description":"CASA ISABEL. Restaurante en Valencia. Disfruta de una exquisita comida mediterranea en la costa de la ciudad de uno de los mejores restaurantes de Valencia","breadcrumb":{"@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2014\/08\/jhmjhmj_1.png","width":640,"height":257},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/el-arroz-de-valencia-en-el-trono-de-la-gastronomia-mediterranea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"El arroz de Valencia, en el trono de la gastronom\u00eda mediterr\u00e1nea"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/66308f25a39c9cb32c4e78cf8cfa36cf","name":"Admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/casaisabel.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa1bef4e15c827fa091464736c1d269687e21ac8972ec35aec466b4aa06b9c8?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/casaisabel.es\/en\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts\/1533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/comments?post=1533"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/posts\/1533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/media\/1534"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/media?parent=1533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/categories?post=1533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casaisabel.es\/en\/wp-json\/wp\/v2\/tags?post=1533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}