{"id":8411,"date":"2023-09-28T16:52:47","date_gmt":"2023-09-28T16:52:47","guid":{"rendered":"https:\/\/casaisabel.upcofly.com\/?page_id=8411"},"modified":"2023-11-29T08:30:34","modified_gmt":"2023-11-29T08:30:34","slug":"weinkarte","status":"publish","type":"page","link":"https:\/\/casaisabel.es\/de\/weinkarte\/","title":{"rendered":"CARTA DE VINOS"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8411\" class=\"elementor elementor-8411\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-131eed50 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-height-default\" data-id=\"131eed50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10038ab0\" data-id=\"10038ab0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76bc56a3 elementor-widget elementor-widget-heading\" data-id=\"76bc56a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">vinos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-609f0310 e-con-full e-flex e-con e-parent\" data-id=\"609f0310\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-737e39ff elementor-widget elementor-widget-html\" data-id=\"737e39ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"menu-casa-isabel\">\n<!--Tintos-->\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Chit\u00f3n Joven<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Rioja -  13.5% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>15\u20ac<\/p><\/div>\n<\/div>\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/murviedro.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Murviedro<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n         <div class=\"description-product\"><p>D.O Valencia - Crianza 13.5% vol. <\/p><\/div>\n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>17\u20ac<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/mala-vida-tinto.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Malavida<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Valencia <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>19\u20ac<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/coto-mayor.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Coto Mayor Crianza <\/p><\/div><div class=\"icons-product\"><\/div>\n           <\/div>\n           <div class=\"description-product\"><p>D.O. Rioja - Tempranillo 13% vol<\/p><\/div>\n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>19\u20ac<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/fuenteespina.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Fuentespina Roble<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Ribera del Duero - Tempranillo 13.75% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>19\u20ac<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/altos-ibericos.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Altos ib\u00e9ricos crianza <\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n        \n            <div class=\"description-product\"><p>D.O. Rioja - Tempranillo 14% vol.<\/p><\/div>\n       \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n\n    <div class=\"price-product\"><p>20\u20ac (3\/4)<\/p><p> 11\u20ac (3\/8)<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/ramon-bilbao.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Ramon Bilbao <\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>Crianza 14% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>21\u20ac<\/p><\/div>\n<\/div>\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/fuenteespina-crianza.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Fuentespina Crianza<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>Tempranillo 13.8% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n    <div class=\"price-product\"><p>21\u20ac<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/kempes.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>El Matador <\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n             <div class=\"description-product\"><p>Vino argentino 14.7% vol.<\/p><\/div>\n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>25\u20ac<\/p><\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n<!--Blancos-->\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/hoya-blanco2.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Hoya del Castillo Blanco<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n         <div class=\"description-product\"><p>D.O Utirel-Requena - Merseguera 13% vol. <\/p><\/div>\n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>15\u20ac<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/4r4u.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>4R 4U<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Rueda - Verdejo 13% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>15\u20ac<\/p><\/div>\n<\/div>\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/verdeo.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Verdeo<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n          <div class=\"description-product\"><p>D.O Rueda - Verdejo 13% vol. <\/p><\/div>\n       \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>18\u20ac<\/p><\/div>\n<\/div>\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/mala-vida.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Malavida Blanco<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Valencia - Moscatel, Meseguera y Verdil 12.5% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>18\u20ac<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/atrium-chardonay.jpeg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Atrium Chardonnay<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n        <div class=\"description-product\"><p>D.O. Pened\u00e9s - 13.5% vol.<\/p><\/div>\n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>20\u20ac<\/p><\/div>\n<\/div>\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/glarima.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Gl\u00e1rima blanco<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n         <div class=\"description-product\"><p>D.O. Somontano - Gew\u00fcrztraminer y Chardonnay 13% vol.<\/p><\/div>\n       \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>21\u20ac<\/p><\/div>\n<\/div>\n\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/pazos-bruxas.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Pazo Das Bruxas<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>Albari\u00f1o 12% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>23\u20ac<\/p><\/div>\n<\/div>\n\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/gran-bazan.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Gran Bazan verde<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Rias Baixax - Albari\u00f1o 13.5% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>25\u20ac<\/p><\/div>\n<\/div>\n\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/alma.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Alma M\u00edstica<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>11% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>Consultar<\/p><\/div>\n<\/div>\n<!--Rosados-->\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/hoya-rosado.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Hoya del Castillo Rosado<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Utirel-Requena - Bobal 12.5% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>15\u20ac<\/p><\/div>\n<\/div>\n  \n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/casta-rosado.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>De Casta Rosado<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Pened\u00e9s 12.5% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>17\u20ac<\/p><\/div>\n<\/div>\n<!--Champagne-->\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/torre-tallada.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Cava Torre Tallada Brut<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Valencia - Macabeo, Parellada, Xarei-io 12% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>19\u20ac<\/p><\/div>\n<\/div>\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/murviedro-cava.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Luna Org\u00e1nic Brut<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p> <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>21\u20ac<\/p><\/div>\n<\/div>\n\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/juve.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Juve & Camps <\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>Reserva de Familia Brut Nature 12% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>35\u20ac<\/p><\/div>\n<\/div>\n\n<div class=\"element-menu\">\n    <div class=\"product\">\n    <div class=\"image-product-vino\"><img decoding=\"async\" src=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/moet.jpg\"><\/div>\n    <div class=\"info-product\">\n        <div class=\"product-name\"><div class=\"namep\"><p>Moet Chandon Brut Imperial<\/p><\/div><div class=\"icons-product\"><\/div><\/div>\n           <div class=\"description-product\"><p>D.O Francia - Champagne 12.5% vol. <\/p><\/div>\n         \n    <\/div>\n<\/div>\n\n<span class=\"price-separator\"><\/span>\n\n    <div class=\"price-product\"><p>65\u20ac<\/p><\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>vinos Chit\u00f3n Joven D.O Rioja &#8211; 13.5% vol. 15\u20ac Murviedro D.O Valencia &#8211; Crianza 13.5% vol. 17\u20ac Malavida D.O Valencia 19\u20ac Coto Mayor Crianza D.O. Rioja &#8211; Tempranillo 13% vol 19\u20ac Fuentespina Roble D.O Ribera del Duero &#8211; Tempranillo 13.75% vol. 19\u20ac Altos ib\u00e9ricos crianza D.O. Rioja &#8211; Tempranillo 14% vol. 20\u20ac (3\/4) 11\u20ac (3\/8) [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-8411","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta de Vinos - Restaurante Casa Isabel<\/title>\n<meta name=\"description\" content=\"Nuestra carta de Vinos en Restaurante Casa Isabel , hemos confeccionado una carta de vinos con m\u00e1s de 20 referencias para todos los gustos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/de\/weinkarte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta de Vinos - Restaurante Casa Isabel\" \/>\n<meta property=\"og:description\" content=\"Nuestra carta de Vinos en Restaurante Casa Isabel , hemos confeccionado una carta de vinos con m\u00e1s de 20 referencias para todos los gustos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/de\/weinkarte\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T08:30:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casaisabel.es\/carta-de-vinos\/\",\"url\":\"https:\/\/casaisabel.es\/carta-de-vinos\/\",\"name\":\"Carta de Vinos - Restaurante Casa Isabel\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casaisabel.es\/carta-de-vinos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/carta-de-vinos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg\",\"datePublished\":\"2023-09-28T16:52:47+00:00\",\"dateModified\":\"2023-11-29T08:30:34+00:00\",\"description\":\"Nuestra carta de Vinos en Restaurante Casa Isabel , hemos confeccionado una carta de vinos con m\u00e1s de 20 referencias para todos los gustos.\",\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/carta-de-vinos\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casaisabel.es\/carta-de-vinos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/casaisabel.es\/carta-de-vinos\/#primaryimage\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/carta-de-vinos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CARTA DE VINOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weinkarte - Restaurant Casa Isabel","description":"Unsere Weinkarte im Restaurant Casa Isabel, wir haben eine Auswahl von \u00fcber 20 Weinen f\u00fcr jeden Geschmack zusammengestellt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/de\/weinkarte\/","og_locale":"de_DE","og_type":"article","og_title":"Carta de Vinos - Restaurante Casa Isabel","og_description":"Nuestra carta de Vinos en Restaurante Casa Isabel , hemos confeccionado una carta de vinos con m\u00e1s de 20 referencias para todos los gustos.","og_url":"https:\/\/casaisabel.es\/de\/weinkarte\/","og_site_name":"Casa Isabel","article_modified_time":"2023-11-29T08:30:34+00:00","og_image":[{"url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaisabel.es\/carta-de-vinos\/","url":"https:\/\/casaisabel.es\/carta-de-vinos\/","name":"Weinkarte - Restaurant Casa Isabel","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaisabel.es\/carta-de-vinos\/#primaryimage"},"image":{"@id":"https:\/\/casaisabel.es\/carta-de-vinos\/#primaryimage"},"thumbnailUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg","datePublished":"2023-09-28T16:52:47+00:00","dateModified":"2023-11-29T08:30:34+00:00","description":"Unsere Weinkarte im Restaurant Casa Isabel, wir haben eine Auswahl von \u00fcber 20 Weinen f\u00fcr jeden Geschmack zusammengestellt.","breadcrumb":{"@id":"https:\/\/casaisabel.es\/carta-de-vinos\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaisabel.es\/carta-de-vinos\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/casaisabel.es\/carta-de-vinos\/#primaryimage","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/10\/chiton.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/carta-de-vinos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"CARTA DE VINOS"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/pages\/8411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/comments?post=8411"}],"version-history":[{"count":0,"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/pages\/8411\/revisions"}],"wp:attachment":[{"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/media?parent=8411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}