{"id":3,"count":133,"description":"","link":"https:\/\/casaisabel.es\/de\/category\/gastronomia\/","name":"Gastronom\u00eda","slug":"gastronomia","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gastronom\u00eda archivos - Casa Isabel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaisabel.es\/de\/category\/gastronomia\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastronom\u00eda archivos - Casa Isabel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaisabel.es\/de\/category\/gastronomia\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Isabel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/casaisabel.es\/category\/gastronomia\/\",\"url\":\"https:\/\/casaisabel.es\/category\/gastronomia\/\",\"name\":\"Gastronom\u00eda archivos - Casa Isabel\",\"isPartOf\":{\"@id\":\"https:\/\/casaisabel.es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/casaisabel.es\/category\/gastronomia\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casaisabel.es\/category\/gastronomia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casaisabel.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastronom\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casaisabel.es\/#website\",\"url\":\"https:\/\/casaisabel.es\/\",\"name\":\"Casa Isabel\",\"description\":\"S\u00f3lo otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/casaisabel.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casaisabel.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casaisabel.es\/#organization\",\"name\":\"Casa Isabel\",\"url\":\"https:\/\/casaisabel.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"contentUrl\":\"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg\",\"width\":211,\"height\":49,\"caption\":\"Casa Isabel\"},\"image\":{\"@id\":\"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastronom\u00eda archivos - Casa Isabel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaisabel.es\/de\/category\/gastronomia\/","og_locale":"de_DE","og_type":"article","og_title":"Gastronom\u00eda archivos - Casa Isabel","og_url":"https:\/\/casaisabel.es\/de\/category\/gastronomia\/","og_site_name":"Casa Isabel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/casaisabel.es\/category\/gastronomia\/","url":"https:\/\/casaisabel.es\/category\/gastronomia\/","name":"Gastronom\u00eda archivos - Casa Isabel","isPartOf":{"@id":"https:\/\/casaisabel.es\/#website"},"breadcrumb":{"@id":"https:\/\/casaisabel.es\/category\/gastronomia\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/casaisabel.es\/category\/gastronomia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casaisabel.es\/"},{"@type":"ListItem","position":2,"name":"Gastronom\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/casaisabel.es\/#website","url":"https:\/\/casaisabel.es\/","name":"Casa Isabel","description":"S\u00f3lo otro sitio de WordPress","publisher":{"@id":"https:\/\/casaisabel.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaisabel.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/casaisabel.es\/#organization","name":"Casa Isabel","url":"https:\/\/casaisabel.es\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/","url":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","contentUrl":"https:\/\/casaisabel.es\/wp-content\/uploads\/2023\/09\/casaIsabel.svg","width":211,"height":49,"caption":"Casa Isabel"},"image":{"@id":"https:\/\/casaisabel.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/casaisabel.es\/de\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}